{"id":8405,"date":"2018-10-11T17:30:20","date_gmt":"2018-10-11T20:30:20","guid":{"rendered":"http:\/\/www.tcheofertas.com.br\/blog\/?p=8405"},"modified":"2018-12-10T09:03:46","modified_gmt":"2018-12-10T11:03:46","slug":"fulaninha-e-dona-coisa","status":"publish","type":"post","link":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/","title":{"rendered":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60!"},"content":{"rendered":"<h2 style=\"text-align: left; line-height: 90%;\"><span style=\"color: #0099aa; font-size: large;\"><strong>BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60!<\/strong><\/span><\/h2>\n<p>Numa\u00a0com\u00e9dia\u00a0n\u00e3o realista<em>, Nathalia Dill e Vilma Mello<\/em>\u00a0vivem, respectivamente,\u00a0<strong>\u201cFulaninha e Dona Coisa\u201d<\/strong>.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.tcheofertas.com.br\/tcheofertas\/upload\/team\/2018\/10\/161231290.jpg\" \/><\/p>\n<p>De um lado est\u00e1\u00a0<strong>Dona Coisa<\/strong>, uma mulher moderna, independente, que prefere manter certa dist\u00e2ncia em suas rela\u00e7\u00f5es.<\/p>\n<p>Do outro est\u00e1\u00a0<strong>Fulaninha<\/strong>, uma jovem com a cabe\u00e7a cheia de sonhos que chega do interior para trabalhar como empregada dom\u00e9stica.<\/p>\n<p><strong>As dificuldades da conviv\u00eancia di\u00e1ria<\/strong>, as trapalhadas de Fulaninha, as confus\u00f5es, o telefone, o elevador e\u00a0o namorado enrolado,\u00a0v\u00e3o te dar gargalhadas!<\/p>\n<p>Compre logo o seu Cupom e n\u00e3o perca este espet\u00e1culo!<\/p>\n<p><a href=\"https:\/\/www.tcheofertas.com.br\/buscar\/FULANINHA\/?idv=app\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-47 size-medium\" src=\"http:\/\/www.tcheofertas.com.br\/blog\/wp-content\/uploads\/2016\/05\/comprar_1240-300x59.png\" alt=\"https:\/\/www.tcheofertas.com.br\/oferta\/diversao-lazer-teatro\/porto-alegre\/teatro-amrigs\/little-john-entretenimento\/peca-emmanuel-xico-xavier-ingresso-desconto-promocao\/?idv=app\" width=\"300\" height=\"59\" srcset=\"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2016\/05\/comprar_1240-300x59.png 300w, https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2016\/05\/comprar_1240-768x150.png 768w, https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2016\/05\/comprar_1240-1024x200.png 1024w, https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2016\/05\/comprar_1240-1200x234.png 1200w, https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2016\/05\/comprar_1240.png 1240w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h3 style=\"line-height: 50%;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small; font-weight: normal;\"> Pre\u00e7os e condi\u00e7\u00f5es<br \/>\nEste \u00e9 um an\u00fancio criado exclusivamente para o aplicativo mobile.<br \/>\nCondi\u00e7\u00f5es de venda podem ser alteradas ap\u00f3s a publica\u00e7\u00e3o deste an\u00fancio.<br \/>\nConfira sempre o pre\u00e7o na p\u00e1gina da oferta antes de concluir sua compra.<br \/>\nCaso haja diferen\u00e7a de pre\u00e7o ou descri\u00e7\u00e3o entre este an\u00fancio e a p\u00e1gina da oferta, a condi\u00e7\u00e3o v\u00e1lida e praticada ser\u00e1 a da p\u00e1gina.<\/span><\/h3>\n<h3 style=\"line-height: 50%;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; font-weight: normal;\">D\u00favidas? <a href=\"https:\/\/www.tcheofertas.com.br\/sac\">SAC TCH\u00ca<\/a><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! Numa\u00a0com\u00e9dia\u00a0n\u00e3o realista, Nathalia Dill e Vilma Mello\u00a0vivem, respectivamente,\u00a0\u201cFulaninha e Dona Coisa\u201d. De um lado est\u00e1\u00a0Dona Coisa, uma mulher moderna, independente, que prefere manter certa dist\u00e2ncia em suas rela\u00e7\u00f5es. Do outro est\u00e1\u00a0Fulaninha, uma jovem com a cabe\u00e7a cheia de sonhos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-8405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiencias-com-desconto-no-sul-do-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! - Blog do Tch\u00ea Ofertas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! - Blog do Tch\u00ea Ofertas\" \/>\n<meta property=\"og:description\" content=\"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! Numa\u00a0com\u00e9dia\u00a0n\u00e3o realista, Nathalia Dill e Vilma Mello\u00a0vivem, respectivamente,\u00a0\u201cFulaninha e Dona Coisa\u201d. De um lado est\u00e1\u00a0Dona Coisa, uma mulher moderna, independente, que prefere manter certa dist\u00e2ncia em suas rela\u00e7\u00f5es. Do outro est\u00e1\u00a0Fulaninha, uma jovem com a cabe\u00e7a cheia de sonhos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Tch\u00ea Ofertas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tcheofertasrs\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-11T20:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-10T11:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2018\/11\/APP-Fulaninha-NHePOA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tch\u00ea Ofertas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tch\u00ea Ofertas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/\"},\"author\":{\"name\":\"Tch\u00ea Ofertas\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7c14046368883d928a49c7e0f756bcd8\"},\"headline\":\"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60!\",\"datePublished\":\"2018-10-11T20:30:20+00:00\",\"dateModified\":\"2018-12-10T11:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/APP-Fulaninha-NHePOA.jpg\",\"articleSection\":[\"Experi\u00eancias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/\",\"url\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/\",\"name\":\"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! - Blog do Tch\u00ea Ofertas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/APP-Fulaninha-NHePOA.jpg\",\"datePublished\":\"2018-10-11T20:30:20+00:00\",\"dateModified\":\"2018-12-10T11:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/APP-Fulaninha-NHePOA.jpg\",\"contentUrl\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/APP-Fulaninha-NHePOA.jpg\",\"width\":720,\"height\":304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/fulaninha-e-dona-coisa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/\",\"name\":\"Blog do Tch\u00ea | Tudo sobre parques, restaurantes e mais com descontos no RS!\",\"description\":\"Restaurantes, parques, cinemas e muitas outras experi\u00eancias no Blog do Tch\u00ea Ofertas. Vem conferir!\",\"publisher\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#organization\",\"name\":\"Tch\u00ea Ofertas\",\"url\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-cropped-cropped-Logo_Tche_Blog-1.png\",\"contentUrl\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-cropped-cropped-Logo_Tche_Blog-1.png\",\"width\":600,\"height\":186,\"caption\":\"Tch\u00ea Ofertas\"},\"image\":{\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tcheofertasrs\",\"https:\\\/\\\/www.instagram.com\\\/tcheofertasrs\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@tcheofertasrs\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqrPD8jFIyEao429MTccWBg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7c14046368883d928a49c7e0f756bcd8\",\"name\":\"Tch\u00ea Ofertas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92a60ab4d55e6aadce1962fc5b583a45306a0a8a955fbb300582a5b9a7942ba2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92a60ab4d55e6aadce1962fc5b583a45306a0a8a955fbb300582a5b9a7942ba2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92a60ab4d55e6aadce1962fc5b583a45306a0a8a955fbb300582a5b9a7942ba2?s=96&d=mm&r=g\",\"caption\":\"Tch\u00ea Ofertas\"},\"url\":\"https:\\\/\\\/tcheofertas.com.br\\\/blog\\\/author\\\/tcheofertas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! - Blog do Tch\u00ea Ofertas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/","og_locale":"pt_BR","og_type":"article","og_title":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! - Blog do Tch\u00ea Ofertas","og_description":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! Numa\u00a0com\u00e9dia\u00a0n\u00e3o realista, Nathalia Dill e Vilma Mello\u00a0vivem, respectivamente,\u00a0\u201cFulaninha e Dona Coisa\u201d. De um lado est\u00e1\u00a0Dona Coisa, uma mulher moderna, independente, que prefere manter certa dist\u00e2ncia em suas rela\u00e7\u00f5es. Do outro est\u00e1\u00a0Fulaninha, uma jovem com a cabe\u00e7a cheia de sonhos [&hellip;]","og_url":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/","og_site_name":"Blog do Tch\u00ea Ofertas","article_publisher":"https:\/\/www.facebook.com\/tcheofertasrs","article_published_time":"2018-10-11T20:30:20+00:00","article_modified_time":"2018-12-10T11:03:46+00:00","og_image":[{"width":720,"height":304,"url":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2018\/11\/APP-Fulaninha-NHePOA.jpg","type":"image\/jpeg"}],"author":"Tch\u00ea Ofertas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Tch\u00ea Ofertas","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#article","isPartOf":{"@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/"},"author":{"name":"Tch\u00ea Ofertas","@id":"https:\/\/tcheofertas.com.br\/blog\/#\/schema\/person\/7c14046368883d928a49c7e0f756bcd8"},"headline":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60!","datePublished":"2018-10-11T20:30:20+00:00","dateModified":"2018-12-10T11:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/tcheofertas.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#primaryimage"},"thumbnailUrl":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2018\/11\/APP-Fulaninha-NHePOA.jpg","articleSection":["Experi\u00eancias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/","url":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/","name":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60! - Blog do Tch\u00ea Ofertas","isPartOf":{"@id":"https:\/\/tcheofertas.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#primaryimage"},"image":{"@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#primaryimage"},"thumbnailUrl":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2018\/11\/APP-Fulaninha-NHePOA.jpg","datePublished":"2018-10-11T20:30:20+00:00","dateModified":"2018-12-10T11:03:46+00:00","breadcrumb":{"@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#primaryimage","url":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2018\/11\/APP-Fulaninha-NHePOA.jpg","contentUrl":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2018\/11\/APP-Fulaninha-NHePOA.jpg","width":720,"height":304},{"@type":"BreadcrumbList","@id":"https:\/\/tcheofertas.com.br\/blog\/fulaninha-e-dona-coisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/tcheofertas.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"BOURBON e FEEVALE: Ingressos para a Pe\u00e7a \u201cFulaninha e Dona Coisa\u201d com Nathalia Dill por R$60!"}]},{"@type":"WebSite","@id":"https:\/\/tcheofertas.com.br\/blog\/#website","url":"https:\/\/tcheofertas.com.br\/blog\/","name":"Blog do Tch\u00ea | Tudo sobre parques, restaurantes e mais com descontos no RS!","description":"Restaurantes, parques, cinemas e muitas outras experi\u00eancias no Blog do Tch\u00ea Ofertas. Vem conferir!","publisher":{"@id":"https:\/\/tcheofertas.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tcheofertas.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/tcheofertas.com.br\/blog\/#organization","name":"Tch\u00ea Ofertas","url":"https:\/\/tcheofertas.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/tcheofertas.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2023\/01\/cropped-cropped-cropped-cropped-Logo_Tche_Blog-1.png","contentUrl":"https:\/\/tcheofertas.com.br\/blog\/wp-content\/uploads\/2023\/01\/cropped-cropped-cropped-cropped-Logo_Tche_Blog-1.png","width":600,"height":186,"caption":"Tch\u00ea Ofertas"},"image":{"@id":"https:\/\/tcheofertas.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tcheofertasrs","https:\/\/www.instagram.com\/tcheofertasrs\/","https:\/\/www.tiktok.com\/@tcheofertasrs","https:\/\/www.youtube.com\/channel\/UCqrPD8jFIyEao429MTccWBg"]},{"@type":"Person","@id":"https:\/\/tcheofertas.com.br\/blog\/#\/schema\/person\/7c14046368883d928a49c7e0f756bcd8","name":"Tch\u00ea Ofertas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/92a60ab4d55e6aadce1962fc5b583a45306a0a8a955fbb300582a5b9a7942ba2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92a60ab4d55e6aadce1962fc5b583a45306a0a8a955fbb300582a5b9a7942ba2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92a60ab4d55e6aadce1962fc5b583a45306a0a8a955fbb300582a5b9a7942ba2?s=96&d=mm&r=g","caption":"Tch\u00ea Ofertas"},"url":"https:\/\/tcheofertas.com.br\/blog\/author\/tcheofertas\/"}]}},"_links":{"self":[{"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/posts\/8405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8405"}],"version-history":[{"count":7,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/posts\/8405\/revisions"}],"predecessor-version":[{"id":8431,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/posts\/8405\/revisions\/8431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/media\/8430"}],"wp:attachment":[{"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tcheofertas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}